{"id":1639,"date":"2017-04-25T11:23:33","date_gmt":"2017-04-25T09:23:33","guid":{"rendered":"http:\/\/www.guion78.com\/wordpress\/?p=1639"},"modified":"2017-04-25T11:25:01","modified_gmt":"2017-04-25T09:25:01","slug":"vlc-videolan-versione-3-0","status":"publish","type":"post","link":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/","title":{"rendered":"VLC di Videolan versione 3.0"},"content":{"rendered":"<p>E\u2019 da febbraio 2015 (uscita della versione 2.2.0) che il noto player multiformato VLC di VideoLAN non ha aggiornamenti corposi, attualmente siamo fermi alla versione 2.2.4 dal 0 giugno 2016.<br \/>\nChiss\u00e0 quanti bug non corretti che circolano nel player, ma quello che spaventa di pi\u00f9 \u00e8 la sua roadmap per la versione 3.0 che doveva uscire intorno a novembre 2016 ma attualmente risulta ferma al 96% della realizzazione senza una nuova vera data di rilascio\u2026.<br \/>\nUn appello a tutti quelli che sanno programmare in Objective C, C++, C, Lua, al fine di supportare lo sviluppo di questo ottimo prodotto, di dare una mano ai programmatori ..<br \/>\nForse lo sviluppo \u00e8 stato messo a dura prova per il supporto dei video a 360\u00b0 una major release la potete vedere a questo link: <a href=\"http:\/\/people.videolan.org\/~jb\/Builds\/360\/\">http:\/\/people.videolan.org\/~jb\/Builds\/360\/<\/a> .<br \/>\nAlla stessa pagina potete pure effettuare una donazione al gruppo per sostenere le spese di sviluppo.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-1640 size-full\" title=\"Vlc\" src=\"http:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover.jpg\" alt=\"vlc di videolan\" width=\"600\" height=\"229\" srcset=\"https:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover.jpg 600w, https:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover-300x115.jpg 300w, https:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover-45x17.jpg 45w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 da febbraio 2015 (uscita della versione 2.2.0) che il noto player multiformato VLC di VideoLAN non ha aggiornamenti corposi, attualmente siamo fermi alla versione 2.2.4 dal 0 giugno 2016. Chiss\u00e0 quanti bug non corretti che circolano nel player, ma quello che spaventa di pi\u00f9 \u00e8 la sua roadmap per la versione 3.0 che doveva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[5,9],"tags":[881,615,614],"class_list":["post-1639","post","type-post","status-publish","format-standard","hentry","category-informatica","category-open-source","tag-player","tag-videolan","tag-vlc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VLC di Videolan versione 3.0 - Guion Matteo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VLC di Videolan versione 3.0 - Guion Matteo\" \/>\n<meta property=\"og:description\" content=\"E\u2019 da febbraio 2015 (uscita della versione 2.2.0) che il noto player multiformato VLC di VideoLAN non ha aggiornamenti corposi, attualmente siamo fermi alla versione 2.2.4 dal 0 giugno 2016. Chiss\u00e0 quanti bug non corretti che circolano nel player, ma quello che spaventa di pi\u00f9 \u00e8 la sua roadmap per la versione 3.0 che doveva [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/\" \/>\n<meta property=\"og:site_name\" content=\"Guion Matteo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BlogMatteoGuion\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-25T09:23:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-25T09:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover.jpg\" \/>\n<meta name=\"author\" content=\"Gua78\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gua78\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/\"},\"author\":{\"name\":\"Gua78\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/dc866ea65964583c162e5476e0ed60e9\"},\"headline\":\"VLC di Videolan versione 3.0\",\"datePublished\":\"2017-04-25T09:23:33+00:00\",\"dateModified\":\"2017-04-25T09:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/\"},\"wordCount\":145,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.guion78.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/cover.jpg\",\"keywords\":[\"player\",\"Videolan\",\"Vlc\"],\"articleSection\":[\"Informatica\",\"Open Source\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/\",\"url\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/\",\"name\":\"VLC di Videolan versione 3.0 - Guion Matteo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.guion78.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/cover.jpg\",\"datePublished\":\"2017-04-25T09:23:33+00:00\",\"dateModified\":\"2017-04-25T09:25:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/dc866ea65964583c162e5476e0ed60e9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.guion78.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/cover.jpg\",\"contentUrl\":\"http:\\\/\\\/www.guion78.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/cover.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2017\\\/04\\\/25\\\/vlc-videolan-versione-3-0\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VLC di Videolan versione 3.0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/\",\"name\":\"Guion Matteo\",\"description\":\"Il Blog ? finalizzato a dare una mano nei problemi informatici di tutti i giorni a tutti quelli a cui pu\u00f2 essere utile, spiegato in modo semplice e passo a passo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/dc866ea65964583c162e5476e0ed60e9\",\"name\":\"Gua78\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg\",\"caption\":\"Gua78\"},\"description\":\"Amministratore del Portale\",\"sameAs\":[\"http:\\\/\\\/www.guion78.com\"],\"url\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VLC di Videolan versione 3.0 - Guion Matteo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/","og_locale":"it_IT","og_type":"article","og_title":"VLC di Videolan versione 3.0 - Guion Matteo","og_description":"E\u2019 da febbraio 2015 (uscita della versione 2.2.0) che il noto player multiformato VLC di VideoLAN non ha aggiornamenti corposi, attualmente siamo fermi alla versione 2.2.4 dal 0 giugno 2016. Chiss\u00e0 quanti bug non corretti che circolano nel player, ma quello che spaventa di pi\u00f9 \u00e8 la sua roadmap per la versione 3.0 che doveva [&hellip;]","og_url":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/","og_site_name":"Guion Matteo","article_publisher":"https:\/\/www.facebook.com\/BlogMatteoGuion\/","article_published_time":"2017-04-25T09:23:33+00:00","article_modified_time":"2017-04-25T09:25:01+00:00","og_image":[{"url":"http:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover.jpg","type":"","width":"","height":""}],"author":"Gua78","twitter_misc":{"Scritto da":"Gua78","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/#article","isPartOf":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/"},"author":{"name":"Gua78","@id":"https:\/\/www.guion78.com\/wordpress\/#\/schema\/person\/dc866ea65964583c162e5476e0ed60e9"},"headline":"VLC di Videolan versione 3.0","datePublished":"2017-04-25T09:23:33+00:00","dateModified":"2017-04-25T09:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/"},"wordCount":145,"commentCount":0,"image":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/#primaryimage"},"thumbnailUrl":"http:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover.jpg","keywords":["player","Videolan","Vlc"],"articleSection":["Informatica","Open Source"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/","url":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/","name":"VLC di Videolan versione 3.0 - Guion Matteo","isPartOf":{"@id":"https:\/\/www.guion78.com\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/#primaryimage"},"image":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/#primaryimage"},"thumbnailUrl":"http:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover.jpg","datePublished":"2017-04-25T09:23:33+00:00","dateModified":"2017-04-25T09:25:01+00:00","author":{"@id":"https:\/\/www.guion78.com\/wordpress\/#\/schema\/person\/dc866ea65964583c162e5476e0ed60e9"},"breadcrumb":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/#primaryimage","url":"http:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover.jpg","contentUrl":"http:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2017\/04\/cover.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2017\/04\/25\/vlc-videolan-versione-3-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.guion78.com\/wordpress\/"},{"@type":"ListItem","position":2,"name":"VLC di Videolan versione 3.0"}]},{"@type":"WebSite","@id":"https:\/\/www.guion78.com\/wordpress\/#website","url":"https:\/\/www.guion78.com\/wordpress\/","name":"Guion Matteo","description":"Il Blog ? finalizzato a dare una mano nei problemi informatici di tutti i giorni a tutti quelli a cui pu\u00f2 essere utile, spiegato in modo semplice e passo a passo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.guion78.com\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.guion78.com\/wordpress\/#\/schema\/person\/dc866ea65964583c162e5476e0ed60e9","name":"Gua78","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg","caption":"Gua78"},"description":"Amministratore del Portale","sameAs":["http:\/\/www.guion78.com"],"url":"https:\/\/www.guion78.com\/wordpress\/blog\/author\/administrator\/"}]}},"views":1561,"_links":{"self":[{"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/posts\/1639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/comments?post=1639"}],"version-history":[{"count":0,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/posts\/1639\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/media?parent=1639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/categories?post=1639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/tags?post=1639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}