{"id":303,"date":"2007-03-23T10:28:39","date_gmt":"2007-03-23T09:28:39","guid":{"rendered":"http:\/\/www.guion78.com\/wordpress\/?p=303"},"modified":"2007-04-01T10:39:12","modified_gmt":"2007-04-01T09:39:12","slug":"24-marzo-stop-alla-tecnologia","status":"publish","type":"post","link":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/","title":{"rendered":"24 Marzo Stop alla tecnologia?"},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" src=\"\/wordpress\/wp-content\/uploads\/2007\/03\/stop.gif\" title=\"stop\" alt=\"stop\" height=\"200\" width=\"200\" \/><\/p>\n<p align=\"left\">Il 24 marzo \u00e8 proclamato il giorno di stop alla tecnologia\u2026. astineza dal computer per un giorno, dopo il fumo, le macchine, il giorno del risparmio energetico, della spesa\u2026. , ora arriva il giorno dello shutdown day\u2026. basta con le feste, meno cavolate e pi\u00f9 fatti concreti.<br \/>\nPensate se tutti spegnessero i computer il mondo tornerebbe all\u2019era della pietra in un millesimo di secondo! IMPENSABILE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 24 marzo \u00e8 proclamato il giorno di stop alla tecnologia\u2026. astineza dal computer per un giorno, dopo il fumo, le macchine, il giorno del risparmio energetico, della spesa\u2026. , ora arriva il giorno dello shutdown day\u2026. basta con le feste, meno cavolate e pi\u00f9 fatti concreti. Pensate se tutti spegnessero i computer il mondo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-303","post","type-post","status-publish","format-standard","hentry","category-curiosita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>24 Marzo Stop alla tecnologia? - Guion Matteo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"24 Marzo Stop alla tecnologia? - Guion Matteo\" \/>\n<meta property=\"og:description\" content=\"Il 24 marzo \u00e8 proclamato il giorno di stop alla tecnologia\u2026. astineza dal computer per un giorno, dopo il fumo, le macchine, il giorno del risparmio energetico, della spesa\u2026. , ora arriva il giorno dello shutdown day\u2026. basta con le feste, meno cavolate e pi\u00f9 fatti concreti. Pensate se tutti spegnessero i computer il mondo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Guion Matteo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BlogMatteoGuion\/\" \/>\n<meta property=\"article:published_time\" content=\"2007-03-23T09:28:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2007-04-01T09:39:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2007\/03\/stop.gif\" \/>\n<meta name=\"author\" content=\"Gua78\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gua78\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/\"},\"author\":{\"name\":\"Gua78\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/dc866ea65964583c162e5476e0ed60e9\"},\"headline\":\"24 Marzo Stop alla tecnologia?\",\"datePublished\":\"2007-03-23T09:28:39+00:00\",\"dateModified\":\"2007-04-01T09:39:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/\"},\"wordCount\":66,\"commentCount\":0,\"articleSection\":[\"Curiosit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/\",\"url\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/\",\"name\":\"24 Marzo Stop alla tecnologia? - Guion Matteo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#website\"},\"datePublished\":\"2007-03-23T09:28:39+00:00\",\"dateModified\":\"2007-04-01T09:39:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/dc866ea65964583c162e5476e0ed60e9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/2007\\\/03\\\/23\\\/24-marzo-stop-alla-tecnologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"24 Marzo Stop alla tecnologia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/\",\"name\":\"Guion Matteo\",\"description\":\"Il Blog ? finalizzato a dare una mano nei problemi informatici di tutti i giorni a tutti quelli a cui pu\u00f2 essere utile, spiegato in modo semplice e passo a passo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/#\\\/schema\\\/person\\\/dc866ea65964583c162e5476e0ed60e9\",\"name\":\"Gua78\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg\",\"caption\":\"Gua78\"},\"description\":\"Amministratore del Portale\",\"sameAs\":[\"http:\\\/\\\/www.guion78.com\"],\"url\":\"https:\\\/\\\/www.guion78.com\\\/wordpress\\\/blog\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"24 Marzo Stop alla tecnologia? - Guion Matteo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/","og_locale":"it_IT","og_type":"article","og_title":"24 Marzo Stop alla tecnologia? - Guion Matteo","og_description":"Il 24 marzo \u00e8 proclamato il giorno di stop alla tecnologia\u2026. astineza dal computer per un giorno, dopo il fumo, le macchine, il giorno del risparmio energetico, della spesa\u2026. , ora arriva il giorno dello shutdown day\u2026. basta con le feste, meno cavolate e pi\u00f9 fatti concreti. Pensate se tutti spegnessero i computer il mondo [&hellip;]","og_url":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/","og_site_name":"Guion Matteo","article_publisher":"https:\/\/www.facebook.com\/BlogMatteoGuion\/","article_published_time":"2007-03-23T09:28:39+00:00","article_modified_time":"2007-04-01T09:39:12+00:00","og_image":[{"url":"https:\/\/www.guion78.com\/wordpress\/wp-content\/uploads\/2007\/03\/stop.gif","type":"","width":"","height":""}],"author":"Gua78","twitter_misc":{"Scritto da":"Gua78"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/#article","isPartOf":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/"},"author":{"name":"Gua78","@id":"https:\/\/www.guion78.com\/wordpress\/#\/schema\/person\/dc866ea65964583c162e5476e0ed60e9"},"headline":"24 Marzo Stop alla tecnologia?","datePublished":"2007-03-23T09:28:39+00:00","dateModified":"2007-04-01T09:39:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/"},"wordCount":66,"commentCount":0,"articleSection":["Curiosit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/","url":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/","name":"24 Marzo Stop alla tecnologia? - Guion Matteo","isPartOf":{"@id":"https:\/\/www.guion78.com\/wordpress\/#website"},"datePublished":"2007-03-23T09:28:39+00:00","dateModified":"2007-04-01T09:39:12+00:00","author":{"@id":"https:\/\/www.guion78.com\/wordpress\/#\/schema\/person\/dc866ea65964583c162e5476e0ed60e9"},"breadcrumb":{"@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.guion78.com\/wordpress\/blog\/2007\/03\/23\/24-marzo-stop-alla-tecnologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.guion78.com\/wordpress\/"},{"@type":"ListItem","position":2,"name":"24 Marzo Stop alla tecnologia?"}]},{"@type":"WebSite","@id":"https:\/\/www.guion78.com\/wordpress\/#website","url":"https:\/\/www.guion78.com\/wordpress\/","name":"Guion Matteo","description":"Il Blog ? finalizzato a dare una mano nei problemi informatici di tutti i giorni a tutti quelli a cui pu\u00f2 essere utile, spiegato in modo semplice e passo a passo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.guion78.com\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.guion78.com\/wordpress\/#\/schema\/person\/dc866ea65964583c162e5476e0ed60e9","name":"Gua78","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e4699b3c931feae00228b34007799d5331f707aa1cfd35b40d0e0637d82cf18?s=96&d=mm&r=pg","caption":"Gua78"},"description":"Amministratore del Portale","sameAs":["http:\/\/www.guion78.com"],"url":"https:\/\/www.guion78.com\/wordpress\/blog\/author\/administrator\/"}]}},"views":1869,"_links":{"self":[{"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/posts\/303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/comments?post=303"}],"version-history":[{"count":0,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/posts\/303\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/media?parent=303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/categories?post=303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guion78.com\/wordpress\/wp-json\/wp\/v2\/tags?post=303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}